{"id":40134,"date":"2023-12-11T13:29:08","date_gmt":"2023-12-11T12:29:08","guid":{"rendered":"https:\/\/foretnature.be\/?post_type=resume-foret-mail&#038;p=40134"},"modified":"2023-12-11T13:29:08","modified_gmt":"2023-12-11T12:29:08","slug":"les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030","status":"publish","type":"resume-foret-mail","link":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/","title":{"rendered":"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ?"},"content":{"rendered":"<p>La d\u00e9signation de sites prot\u00e9g\u00e9s permet de maintenir des noyaux d\u2019habitats et de populations \u00e0 partir desquels un red\u00e9ploiement des esp\u00e8ces est possible. Ces noyaux peuvent \u00eatre des r\u00e9serves naturelles domaniales et agr\u00e9es, des zones humides d\u2019int\u00e9r\u00eat biologique, des cavit\u00e9s souterraines d\u2019int\u00e9r\u00eat scientifique et des r\u00e9serves int\u00e9grales en for\u00eat.<\/p>\n<p>En Wallonie, ce r\u00e9seau de sites naturels prot\u00e9g\u00e9s s\u2019\u00e9toffe mais reste peu \u00e9tendu, il couvrait 1,6 % du territoire wallon en mai 2022. Outre la disponibilit\u00e9 des terrains vis\u00e9s, il reste la question de la valeur v\u00e9nale et des budgets disponibles, ce qui conditionne la rapidit\u00e9 de renforcement du r\u00e9seau actuel.<\/p>\n<p>Le Plan de relance de la Wallonie pr\u00e9voit de renforcer ce r\u00e9seau ainsi que le maillage entre les aires prot\u00e9g\u00e9es. Cela rejoint la strat\u00e9gie biodiversit\u00e9 360\u00b0 qui vise notamment un r\u00e9seau couvrant 5 % du territoire en 2030.<\/p>\n<p>En Wallonie, sur base de donn\u00e9es scientifiques, le SPW ARNE r\u00e9pertorie les sites abritant des habitats et des populations d\u2019esp\u00e8ces prot\u00e9g\u00e9s, rares ou menac\u00e9s ou constituant des exemples remarquables d\u2019associations d\u2019esp\u00e8ces en excellent \u00e9tat de conservation. Ce sont \u00ab les sites de grand int\u00e9r\u00eat biologique \u00bb (SGIB). En mars 2023, 3 138 sites \u00e9taient r\u00e9f\u00e9renc\u00e9s dans cette base de donn\u00e9es, pour une superficie de 151 247 hectares. Cela repr\u00e9sente 8,9 % du territoire wallon.<\/p>","protected":false},"excerpt":{"rendered":"<p>La d\u00e9signation de sites prot\u00e9g\u00e9s permet de maintenir des noyaux d\u2019habitats et de populations \u00e0 partir desquels un red\u00e9ploiement des esp\u00e8ces est possible. Ces noyaux peuvent \u00eatre des r\u00e9serves naturelles domaniales et agr\u00e9es, des zones humides d\u2019int\u00e9r\u00eat biologique, des cavit\u00e9s souterraines d\u2019int\u00e9r\u00eat scientifique et des r\u00e9serves int\u00e9grales en for\u00eat. En Wallonie, ce r\u00e9seau de sites [&hellip;]<\/p>","protected":false},"featured_media":40107,"template":"","categories":[50],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ? - For\u00eat.Nature<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ? - For\u00eat.Nature\" \/>\n<meta property=\"og:description\" content=\"La d\u00e9signation de sites prot\u00e9g\u00e9s permet de maintenir des noyaux d\u2019habitats et de populations \u00e0 partir desquels un red\u00e9ploiement des esp\u00e8ces est possible. Ces noyaux peuvent \u00eatre des r\u00e9serves naturelles domaniales et agr\u00e9es, des zones humides d\u2019int\u00e9r\u00eat biologique, des cavit\u00e9s souterraines d\u2019int\u00e9r\u00eat scientifique et des r\u00e9serves int\u00e9grales en for\u00eat. En Wallonie, ce r\u00e9seau de sites [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/\" \/>\n<meta property=\"og:site_name\" content=\"For\u00eat.Nature\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/\",\"url\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/\",\"name\":\"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ? - For\u00eat.Nature\",\"isPartOf\":{\"@id\":\"https:\/\/foretnature.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg\",\"datePublished\":\"2023-12-11T12:29:08+00:00\",\"dateModified\":\"2023-12-11T12:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#primaryimage\",\"url\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg\",\"contentUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg\",\"width\":900,\"height\":541},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/foretnature.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foretnature.be\/#website\",\"url\":\"https:\/\/foretnature.be\/\",\"name\":\"For\u00eat.Nature\",\"description\":\"Une \u00e9quipe technique au service de la for\u00eat\",\"publisher\":{\"@id\":\"https:\/\/foretnature.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foretnature.be\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foretnature.be\/#organization\",\"name\":\"For\u00eat.Nature\",\"url\":\"https:\/\/foretnature.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/foretnature.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png\",\"contentUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png\",\"width\":300,\"height\":151,\"caption\":\"For\u00eat.Nature\"},\"image\":{\"@id\":\"https:\/\/foretnature.be\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ? - For\u00eat.Nature","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/","og_locale":"en_GB","og_type":"article","og_title":"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ? - For\u00eat.Nature","og_description":"La d\u00e9signation de sites prot\u00e9g\u00e9s permet de maintenir des noyaux d\u2019habitats et de populations \u00e0 partir desquels un red\u00e9ploiement des esp\u00e8ces est possible. Ces noyaux peuvent \u00eatre des r\u00e9serves naturelles domaniales et agr\u00e9es, des zones humides d\u2019int\u00e9r\u00eat biologique, des cavit\u00e9s souterraines d\u2019int\u00e9r\u00eat scientifique et des r\u00e9serves int\u00e9grales en for\u00eat. En Wallonie, ce r\u00e9seau de sites [&hellip;]","og_url":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/","og_site_name":"For\u00eat.Nature","og_image":[{"width":900,"height":541,"url":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/","url":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/","name":"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ? - For\u00eat.Nature","isPartOf":{"@id":"https:\/\/foretnature.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#primaryimage"},"image":{"@id":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#primaryimage"},"thumbnailUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg","datePublished":"2023-12-11T12:29:08+00:00","dateModified":"2023-12-11T12:29:08+00:00","breadcrumb":{"@id":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#primaryimage","url":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg","contentUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2511.jpg","width":900,"height":541},{"@type":"BreadcrumbList","@id":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-sites-proteges-en-wallonie-de-16-a-5-du-territoire-en-2030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/foretnature.be\/"},{"@type":"ListItem","position":2,"name":"Les sites prot\u00e9g\u00e9s en Wallonie, de 1,6 \u00e0 5 % du territoire en 2030 ?"}]},{"@type":"WebSite","@id":"https:\/\/foretnature.be\/#website","url":"https:\/\/foretnature.be\/","name":"For\u00eat.Nature","description":"Une \u00e9quipe technique au service de la for\u00eat","publisher":{"@id":"https:\/\/foretnature.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foretnature.be\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/foretnature.be\/#organization","name":"For\u00eat.Nature","url":"https:\/\/foretnature.be\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foretnature.be\/#\/schema\/logo\/image\/","url":"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png","contentUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png","width":300,"height":151,"caption":"For\u00eat.Nature"},"image":{"@id":"https:\/\/foretnature.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/40134"}],"collection":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail"}],"about":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/types\/resume-foret-mail"}],"version-history":[{"count":1,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/40134\/revisions"}],"predecessor-version":[{"id":40135,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/40134\/revisions\/40135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/media\/40107"}],"wp:attachment":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/media?parent=40134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/categories?post=40134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}