{"id":40128,"date":"2023-12-11T13:23:42","date_gmt":"2023-12-11T12:23:42","guid":{"rendered":"https:\/\/foretnature.be\/?post_type=resume-foret-mail&#038;p=40128"},"modified":"2023-12-11T13:23:42","modified_gmt":"2023-12-11T12:23:42","slug":"les-souches-25-du-volume-de-bois-mort-en-foret","status":"publish","type":"resume-foret-mail","link":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/","title":{"rendered":"Les souches, 25 % du volume de bois mort en for\u00eat !"},"content":{"rendered":"<p>L\u2019importance du bois mort en for\u00eat n\u2019est plus \u00e0 d\u00e9montrer. Les recommandations portent g\u00e9n\u00e9ralement sur les bois morts au sol ou sur pied, oubliant l\u2019importance d\u2019\u00e9galement conserver les souches en for\u00eat. Or, leur volume peut \u00eatre consid\u00e9rable en for\u00eat. Une \u00e9tude suisse s\u2019est pench\u00e9e sur la question, avec pour objectif d\u2019\u00e9tablir le volume et la biomasse que repr\u00e9sentent les souches dans l\u2019Inventaire Forestier National Suisse. Il en ressort que la contribution des souches au volume total de bois mort en for\u00eat s\u2019\u00e9l\u00e8ve \u00e0 environ 25 % ! Les souches, en plus des autres formes de bois mort, ont donc aussi leur r\u00f4le \u00e0 jouer, notamment dans la pr\u00e9servation de la biodiversit\u00e9 foresti\u00e8re et des stocks de carbone.<\/p>\n<p>La mani\u00e8re d\u2019inventorier ces souches influence beaucoup le r\u00e9sultat des comptages. Ainsi, les chercheurs montrent que la prise en compte d\u2019une hauteur de souche de 30 cm et du diam\u00e8tre \u00e0 hauteur de poitrine de l\u2019arbre concern\u00e9 provoque une sous-estimation des volumes r\u00e9els. En effet, le diam\u00e8tre de la souche est plus important que celui \u00e0 hauteur de poitrine, et sa hauteur peut d\u00e9passer 30 cm. Il y a donc une n\u00e9cessit\u00e9 d\u2019ajouter des mesures suppl\u00e9mentaires.<\/p>\n<p>Les chercheurs proposent ainsi une m\u00e9thode bas\u00e9e sur deux mesures de hauteur et deux mesures du diam\u00e8tre, pour plus de pr\u00e9cision lors des inventaires. Les souches se d\u00e9composent lentement, avec un temps de r\u00e9tention minimum estim\u00e9 \u00e0 35 ans, comme pour certains arbres sur pied. Une m\u00e9thode d\u2019inventaire correcte est donc capitale pour conna\u00eetre les volumes r\u00e9els de bois mort dans sa for\u00eat.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019importance du bois mort en for\u00eat n\u2019est plus \u00e0 d\u00e9montrer. Les recommandations portent g\u00e9n\u00e9ralement sur les bois morts au sol ou sur pied, oubliant l\u2019importance d\u2019\u00e9galement conserver les souches en for\u00eat. Or, leur volume peut \u00eatre consid\u00e9rable en for\u00eat. Une \u00e9tude suisse s\u2019est pench\u00e9e sur la question, avec pour objectif d\u2019\u00e9tablir le volume et la [&hellip;]<\/p>","protected":false},"featured_media":40104,"template":"","categories":[50],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les souches, 25 % du volume de bois mort en for\u00eat ! - For\u00eat.Nature<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les souches, 25 % du volume de bois mort en for\u00eat ! - For\u00eat.Nature\" \/>\n<meta property=\"og:description\" content=\"L\u2019importance du bois mort en for\u00eat n\u2019est plus \u00e0 d\u00e9montrer. Les recommandations portent g\u00e9n\u00e9ralement sur les bois morts au sol ou sur pied, oubliant l\u2019importance d\u2019\u00e9galement conserver les souches en for\u00eat. Or, leur volume peut \u00eatre consid\u00e9rable en for\u00eat. Une \u00e9tude suisse s\u2019est pench\u00e9e sur la question, avec pour objectif d\u2019\u00e9tablir le volume et la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/\" \/>\n<meta property=\"og:site_name\" content=\"For\u00eat.Nature\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/\",\"url\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/\",\"name\":\"Les souches, 25 % du volume de bois mort en for\u00eat ! - For\u00eat.Nature\",\"isPartOf\":{\"@id\":\"https:\/\/foretnature.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg\",\"datePublished\":\"2023-12-11T12:23:42+00:00\",\"dateModified\":\"2023-12-11T12:23:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#primaryimage\",\"url\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg\",\"contentUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/foretnature.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les souches, 25 % du volume de bois mort en for\u00eat !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foretnature.be\/#website\",\"url\":\"https:\/\/foretnature.be\/\",\"name\":\"For\u00eat.Nature\",\"description\":\"Une \u00e9quipe technique au service de la for\u00eat\",\"publisher\":{\"@id\":\"https:\/\/foretnature.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foretnature.be\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foretnature.be\/#organization\",\"name\":\"For\u00eat.Nature\",\"url\":\"https:\/\/foretnature.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/foretnature.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png\",\"contentUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png\",\"width\":300,\"height\":151,\"caption\":\"For\u00eat.Nature\"},\"image\":{\"@id\":\"https:\/\/foretnature.be\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les souches, 25 % du volume de bois mort en for\u00eat ! - For\u00eat.Nature","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/","og_locale":"en_GB","og_type":"article","og_title":"Les souches, 25 % du volume de bois mort en for\u00eat ! - For\u00eat.Nature","og_description":"L\u2019importance du bois mort en for\u00eat n\u2019est plus \u00e0 d\u00e9montrer. Les recommandations portent g\u00e9n\u00e9ralement sur les bois morts au sol ou sur pied, oubliant l\u2019importance d\u2019\u00e9galement conserver les souches en for\u00eat. Or, leur volume peut \u00eatre consid\u00e9rable en for\u00eat. Une \u00e9tude suisse s\u2019est pench\u00e9e sur la question, avec pour objectif d\u2019\u00e9tablir le volume et la [&hellip;]","og_url":"https:\/\/foretnature.be\/en\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/","og_site_name":"For\u00eat.Nature","og_image":[{"width":900,"height":675,"url":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/","url":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/","name":"Les souches, 25 % du volume de bois mort en for\u00eat ! - For\u00eat.Nature","isPartOf":{"@id":"https:\/\/foretnature.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#primaryimage"},"image":{"@id":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#primaryimage"},"thumbnailUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg","datePublished":"2023-12-11T12:23:42+00:00","dateModified":"2023-12-11T12:23:42+00:00","breadcrumb":{"@id":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#primaryimage","url":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg","contentUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2023\/12\/2508.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/foretnature.be\/resume-foret-mail\/les-souches-25-du-volume-de-bois-mort-en-foret\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/foretnature.be\/"},{"@type":"ListItem","position":2,"name":"Les souches, 25 % du volume de bois mort en for\u00eat !"}]},{"@type":"WebSite","@id":"https:\/\/foretnature.be\/#website","url":"https:\/\/foretnature.be\/","name":"For\u00eat.Nature","description":"Une \u00e9quipe technique au service de la for\u00eat","publisher":{"@id":"https:\/\/foretnature.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foretnature.be\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/foretnature.be\/#organization","name":"For\u00eat.Nature","url":"https:\/\/foretnature.be\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foretnature.be\/#\/schema\/logo\/image\/","url":"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png","contentUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png","width":300,"height":151,"caption":"For\u00eat.Nature"},"image":{"@id":"https:\/\/foretnature.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/40128"}],"collection":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail"}],"about":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/types\/resume-foret-mail"}],"version-history":[{"count":1,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/40128\/revisions"}],"predecessor-version":[{"id":40129,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/40128\/revisions\/40129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/media\/40104"}],"wp:attachment":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/media?parent=40128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/categories?post=40128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}