{"id":34323,"date":"2021-09-10T11:45:22","date_gmt":"2021-09-10T09:45:22","guid":{"rendered":"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/"},"modified":"2021-09-10T11:45:22","modified_gmt":"2021-09-10T09:45:22","slug":"video-lislande-cultive-de-nouvelles-forets","status":"publish","type":"resume-foret-mail","link":"https:\/\/foretnature.be\/en\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/","title":{"rendered":"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats"},"content":{"rendered":"<p>Le paysage islandais a beaucoup \u00e9volu\u00e9 depuis 1000 ans. L\u2019arriv\u00e9e des Vikings au 9e si\u00e8cle a engendr\u00e9 une d\u00e9forestation massive qui a provoqu\u00e9 une importante \u00e9rosion des sols mena\u00e7ant l\u2019Islande de d\u00e9sertification.<br \/>\nAujourd\u2019hui, le service forestier veut relever l\u2019immense challenge de faire revenir la for\u00eat. Progressivement, gr\u00e2ce \u00e0 l\u2019aide de nombreuses professions en relation avec la terre et l\u2019environnement, l\u2019Islande reverdit.<br \/>\nNational Geographic.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le paysage islandais a beaucoup \u00e9volu\u00e9 depuis 1000 ans. L\u2019arriv\u00e9e des Vikings au 9e si\u00e8cle a engendr\u00e9 une d\u00e9forestation massive qui a provoqu\u00e9 une importante \u00e9rosion des sols mena\u00e7ant l\u2019Islande de d\u00e9sertification. Aujourd\u2019hui, le service forestier veut relever l\u2019immense challenge de faire revenir la for\u00eat. Progressivement, gr\u00e2ce \u00e0 l\u2019aide de nombreuses professions en relation avec [&hellip;]<\/p>","protected":false},"featured_media":0,"template":"","categories":[50],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats - For\u00eat.Nature<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foretnature.be\/en\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats - For\u00eat.Nature\" \/>\n<meta property=\"og:description\" content=\"Le paysage islandais a beaucoup \u00e9volu\u00e9 depuis 1000 ans. L\u2019arriv\u00e9e des Vikings au 9e si\u00e8cle a engendr\u00e9 une d\u00e9forestation massive qui a provoqu\u00e9 une importante \u00e9rosion des sols mena\u00e7ant l\u2019Islande de d\u00e9sertification. Aujourd\u2019hui, le service forestier veut relever l\u2019immense challenge de faire revenir la for\u00eat. Progressivement, gr\u00e2ce \u00e0 l\u2019aide de nombreuses professions en relation avec [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foretnature.be\/en\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/\" \/>\n<meta property=\"og:site_name\" content=\"For\u00eat.Nature\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/\",\"url\":\"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/\",\"name\":\"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats - For\u00eat.Nature\",\"isPartOf\":{\"@id\":\"https:\/\/foretnature.be\/#website\"},\"datePublished\":\"2021-09-10T09:45:22+00:00\",\"dateModified\":\"2021-09-10T09:45:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/foretnature.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foretnature.be\/#website\",\"url\":\"https:\/\/foretnature.be\/\",\"name\":\"For\u00eat.Nature\",\"description\":\"Une \u00e9quipe technique au service de la for\u00eat\",\"publisher\":{\"@id\":\"https:\/\/foretnature.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foretnature.be\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foretnature.be\/#organization\",\"name\":\"For\u00eat.Nature\",\"url\":\"https:\/\/foretnature.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/foretnature.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png\",\"contentUrl\":\"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png\",\"width\":300,\"height\":151,\"caption\":\"For\u00eat.Nature\"},\"image\":{\"@id\":\"https:\/\/foretnature.be\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats - For\u00eat.Nature","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foretnature.be\/en\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/","og_locale":"en_GB","og_type":"article","og_title":"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats - For\u00eat.Nature","og_description":"Le paysage islandais a beaucoup \u00e9volu\u00e9 depuis 1000 ans. L\u2019arriv\u00e9e des Vikings au 9e si\u00e8cle a engendr\u00e9 une d\u00e9forestation massive qui a provoqu\u00e9 une importante \u00e9rosion des sols mena\u00e7ant l\u2019Islande de d\u00e9sertification. Aujourd\u2019hui, le service forestier veut relever l\u2019immense challenge de faire revenir la for\u00eat. Progressivement, gr\u00e2ce \u00e0 l\u2019aide de nombreuses professions en relation avec [&hellip;]","og_url":"https:\/\/foretnature.be\/en\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/","og_site_name":"For\u00eat.Nature","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/","url":"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/","name":"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats - For\u00eat.Nature","isPartOf":{"@id":"https:\/\/foretnature.be\/#website"},"datePublished":"2021-09-10T09:45:22+00:00","dateModified":"2021-09-10T09:45:22+00:00","breadcrumb":{"@id":"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/foretnature.be\/resume-foret-mail\/video-lislande-cultive-de-nouvelles-forets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/foretnature.be\/"},{"@type":"ListItem","position":2,"name":"Vid\u00e9o. L\u2019Islande cultive de nouvelles for\u00eats"}]},{"@type":"WebSite","@id":"https:\/\/foretnature.be\/#website","url":"https:\/\/foretnature.be\/","name":"For\u00eat.Nature","description":"Une \u00e9quipe technique au service de la for\u00eat","publisher":{"@id":"https:\/\/foretnature.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foretnature.be\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/foretnature.be\/#organization","name":"For\u00eat.Nature","url":"https:\/\/foretnature.be\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/foretnature.be\/#\/schema\/logo\/image\/","url":"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png","contentUrl":"https:\/\/foretnature.be\/wp-content\/uploads\/2021\/01\/logoFOblanc.png","width":300,"height":151,"caption":"For\u00eat.Nature"},"image":{"@id":"https:\/\/foretnature.be\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/34323"}],"collection":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail"}],"about":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/types\/resume-foret-mail"}],"version-history":[{"count":0,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/resume-foret-mail\/34323\/revisions"}],"wp:attachment":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/media?parent=34323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/categories?post=34323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}