{"id":40663,"date":"2024-03-01T10:46:50","date_gmt":"2024-03-01T09:46:50","guid":{"rendered":"https:\/\/foretnature.be\/bibliotheque\/jardinage-cultural-et-methode-de-controle-domaine-forestier-de-couvet-commune-de-val-travers\/"},"modified":"2024-03-01T10:46:50","modified_gmt":"2024-03-01T09:46:50","slug":"jardinage-cultural-et-methode-de-controle-domaine-forestier-de-couvet-commune-de-val-travers","status":"publish","type":"bibliotheque","link":"https:\/\/foretnature.be\/en\/bibliotheque\/jardinage-cultural-et-methode-de-controle-domaine-forestier-de-couvet-commune-de-val-travers\/","title":{"rendered":"Jardinage cultural et m\u00e9thode de contr\u00f4le. Domaine forestier de Couvet (Commune de Val-travers)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","categories":[32],"tags":[],"class_list":["post-40663","bibliotheque","type-bibliotheque","status-publish","hentry","category-nouveaute"],"acf":[],"_links":{"self":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/bibliotheque\/40663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/bibliotheque"}],"about":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/types\/bibliotheque"}],"wp:attachment":[{"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/media?parent=40663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/categories?post=40663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foretnature.be\/en\/wp-json\/wp\/v2\/tags?post=40663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}